{"id":22329,"date":"2022-08-15T22:44:48","date_gmt":"2022-08-16T01:44:48","guid":{"rendered":"https:\/\/www.valormais.com.br\/?p=22329"},"modified":"2022-08-15T22:44:48","modified_gmt":"2022-08-16T01:44:48","slug":"advogado-em-santo-amaro-2","status":"publish","type":"post","link":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/","title":{"rendered":"Advogado em Santo Amaro"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice do Conte\u00fado<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#Advogado_em_Santo_Amaro\" >Advogado em Santo Amaro<\/a><ul class='ez-toc-list-level-2' ><li class='ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#Advogado_em_Santo_Amaro-2\" >Advogado em Santo Amaro<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#Advogado_Trabalhista_em_Santo_Amaro\" >Advogado Trabalhista em Santo Amaro<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1><span class=\"ez-toc-section\" id=\"Advogado_em_Santo_Amaro\"><\/span>Advogado em Santo Amaro<span class=\"ez-toc-section-end\"><\/span><\/h1>\n<blockquote><p><strong>Empresa:<\/strong> Luis Rivero Advogado<\/p>\n<p><strong>Telefone:<\/strong> (11) 98553-5701<\/p>\n<p><strong>Endere\u00e7o:<\/strong> Rua Vitorino de Morais, 367 \u2013 Ch\u00e1cara Santo Ant\u00f4nio \u2013 SP \u2013 CEP 04714-030<\/p>\n<p><strong>E-mail:<\/strong> luis.rivero@icloud.com<\/p>\n<p><strong>Site:<\/strong> <a href=\"https:\/\/riveroadvogado.wixsite.com\/advocacia\">https:\/\/riveroadvogado.wixsite.com\/advocacia<\/a><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Advogado_em_Santo_Amaro-2\"><\/span>Advogado em Santo Amaro<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Servi\u00e7os Advocat\u00edcios, Assessoria Jur\u00eddica<\/p>\n<p><strong>Pense nas principais d\u00favidas que as pessoas tem quando est\u00e3o pensando em consumir o seu produto ou servi\u00e7o, e cite aqui as principais perguntas e as respostas.<\/strong><\/p>\n<p>Qual a sua especialidade? \u00c1reas: C\u00edvel, Trabalhista, Fam\u00edlia e Previdenci\u00e1ria<\/p>\n<p><strong>Se voc\u00ea tem um neg\u00f3cio f\u00edsico, informe o seu hor\u00e1rio de atendimento.<\/strong><\/p>\n<p>Atendimento de segunda a sexta, das 9:00 \u00e0s 12h e das 13:30 \u00e0s 18h<\/p>\n<p><strong>Se voc\u00ea tem um neg\u00f3cio f\u00edsico, fale um pouco sobre suas instala\u00e7\u00f5es. Diga como chegar, pontos de refer\u00eancia, sua estrutura. Enfim, tudo que acredita ser um diferencial.<\/strong><\/p>\n<p>\u00d3tima localiza\u00e7\u00e3o, pr\u00f3ximo ao Borba Gato, travessa da rua Am\u00e9rico Brasiliense.<\/p>\n<p><strong>Quais as pessoas que normalmente consomem seu produto ou servi\u00e7o?<\/strong><\/p>\n<p>Qualquer pessoa, f\u00edsica ou jur\u00eddica.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Advogado_Trabalhista_em_Santo_Amaro\"><\/span>Advogado Trabalhista em Santo Amaro<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<blockquote><p><strong>Empresa:<\/strong> Luis Rivero Advogado<\/p>\n<p><strong>Telefone:<\/strong> (11) 98553-5701<\/p>\n<p><strong>Endere\u00e7o:<\/strong> Rua Vitorino de Morais, 367 \u2013 Ch\u00e1cara Santo Ant\u00f4nio \u2013 SP \u2013 CEP 04714-030<\/p>\n<p><strong>E-mail:<\/strong> luis.rivero@icloud.com<\/p>\n<p><strong>Site:<\/strong> <a href=\"https:\/\/riveroadvogado.wixsite.com\/advocacia\">https:\/\/riveroadvogado.wixsite.com\/advocacia<\/a><\/p><\/blockquote>\n<p>Solicite um Or\u00e7amento<br \/>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1033-o1\" lang=\"pt-BR\" dir=\"ltr\" data-wpcf7-id=\"1033\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/blog\/wp-json\/wp\/v2\/posts\/22329#wpcf7-f1033-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rios de contato\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1033\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_BR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1033-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.6\" \/>\n<\/fieldset>\n<div style=\"display:none;\">\n\t<p><input type=\"hidden\" name=\"your-subject\" value=\"Or\u00e7amento\" \/>\n\t<span class=\"wpcf7-form-control-wrap URL\" data-name=\"URL\"><input type=\"hidden\" name=\"URL\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.valormais.com.br\/blog\/blog\/wp-json\/wp\/v2\/posts\/22329\"><\/span>\n\t<span class=\"wpcf7-form-control-wrap email_cliente\" data-name=\"email_cliente\"><input type=\"hidden\" name=\"email_cliente\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\"><\/span>\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-240-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefone\" value=\"\" type=\"text\" name=\"text-240-tel\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Digite aqui o que voc\u00ea precisa...\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>[recaptcha]\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR OR\u00c7AMENTO\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on the_excerpt --><!-- AddThis Share Buttons generic via filter on the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":22420,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"o","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-22329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Advogado em Santo Amaro - Lu\u00eds Rivero Advogado<\/title>\n<meta name=\"description\" content=\"Lu\u00eds Rivero Advogado especialista nas \u00e1reas Trabalhistas, Previdenci\u00e1ria e C\u00edvel. Entre em contato conosco (11) 98553-5701\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Advogado em Santo Amaro\" \/>\n<meta property=\"og:description\" content=\"Lu\u00eds Rivero Advogado especialista nas \u00e1reas Trabalhistas, Previdenci\u00e1ria e C\u00edvel. Entre em contato conosco (11) 98553-5701\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/\" \/>\n<meta property=\"og:site_name\" content=\"VALORMAIS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ValorMais\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T01:44:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FOCO Assessoria Empresarial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@valormais\" \/>\n<meta name=\"twitter:site\" content=\"@valormais\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FOCO Assessoria Empresarial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/\"},\"author\":{\"name\":\"FOCO Assessoria Empresarial\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/1d2d001548213ad6cfcc835eeea4ffac\"},\"headline\":\"Advogado em Santo Amaro\",\"datePublished\":\"2022-08-16T01:44:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/\"},\"wordCount\":230,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg\",\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/\",\"url\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/\",\"name\":\"Advogado em Santo Amaro - Lu\u00eds Rivero Advogado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg\",\"datePublished\":\"2022-08-16T01:44:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/1d2d001548213ad6cfcc835eeea4ffac\"},\"description\":\"Lu\u00eds Rivero Advogado especialista nas \u00e1reas Trabalhistas, Previdenci\u00e1ria e C\u00edvel. Entre em contato conosco (11) 98553-5701\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg\",\"width\":567,\"height\":707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/artigos\\\/advogado-em-santo-amaro-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artigos\",\"item\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/categorias\\\/artigos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Advogado em Santo Amaro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/\",\"name\":\"VALORMAIS\",\"description\":\"Solu\u00e7\u00f5es Digitais Inovadoras\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/1d2d001548213ad6cfcc835eeea4ffac\",\"name\":\"FOCO Assessoria Empresarial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/799cc92a2f706b95d6e8136b55400b10378ef83f655b24689bc4f30eea59233d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/799cc92a2f706b95d6e8136b55400b10378ef83f655b24689bc4f30eea59233d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/799cc92a2f706b95d6e8136b55400b10378ef83f655b24689bc4f30eea59233d?s=96&d=mm&r=g\",\"caption\":\"FOCO Assessoria Empresarial\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Advogado em Santo Amaro - Lu\u00eds Rivero Advogado","description":"Lu\u00eds Rivero Advogado especialista nas \u00e1reas Trabalhistas, Previdenci\u00e1ria e C\u00edvel. Entre em contato conosco (11) 98553-5701","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Advogado em Santo Amaro","og_description":"Lu\u00eds Rivero Advogado especialista nas \u00e1reas Trabalhistas, Previdenci\u00e1ria e C\u00edvel. Entre em contato conosco (11) 98553-5701","og_url":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/","og_site_name":"VALORMAIS","article_publisher":"https:\/\/www.facebook.com\/ValorMais","article_published_time":"2022-08-16T01:44:48+00:00","og_image":[{"width":567,"height":707,"url":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg","type":"image\/jpeg"}],"author":"FOCO Assessoria Empresarial","twitter_card":"summary_large_image","twitter_creator":"@valormais","twitter_site":"@valormais","twitter_misc":{"Escrito por":"FOCO Assessoria Empresarial","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#article","isPartOf":{"@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/"},"author":{"name":"FOCO Assessoria Empresarial","@id":"https:\/\/www.valormais.com.br\/blog\/#\/schema\/person\/1d2d001548213ad6cfcc835eeea4ffac"},"headline":"Advogado em Santo Amaro","datePublished":"2022-08-16T01:44:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/"},"wordCount":230,"commentCount":0,"image":{"@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg","articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/","url":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/","name":"Advogado em Santo Amaro - Lu\u00eds Rivero Advogado","isPartOf":{"@id":"https:\/\/www.valormais.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#primaryimage"},"image":{"@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg","datePublished":"2022-08-16T01:44:48+00:00","author":{"@id":"https:\/\/www.valormais.com.br\/blog\/#\/schema\/person\/1d2d001548213ad6cfcc835eeea4ffac"},"description":"Lu\u00eds Rivero Advogado especialista nas \u00e1reas Trabalhistas, Previdenci\u00e1ria e C\u00edvel. Entre em contato conosco (11) 98553-5701","breadcrumb":{"@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#primaryimage","url":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg","contentUrl":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2019\/04\/WhatsApp-Image-2019-04-18-at-09.16.03.jpeg","width":567,"height":707},{"@type":"BreadcrumbList","@id":"https:\/\/www.valormais.com.br\/blog\/artigos\/advogado-em-santo-amaro-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.valormais.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Artigos","item":"https:\/\/www.valormais.com.br\/blog\/categorias\/artigos\/"},{"@type":"ListItem","position":3,"name":"Advogado em Santo Amaro"}]},{"@type":"WebSite","@id":"https:\/\/www.valormais.com.br\/blog\/#website","url":"https:\/\/www.valormais.com.br\/blog\/","name":"VALORMAIS","description":"Solu\u00e7\u00f5es Digitais Inovadoras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valormais.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.valormais.com.br\/blog\/#\/schema\/person\/1d2d001548213ad6cfcc835eeea4ffac","name":"FOCO Assessoria Empresarial","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/799cc92a2f706b95d6e8136b55400b10378ef83f655b24689bc4f30eea59233d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/799cc92a2f706b95d6e8136b55400b10378ef83f655b24689bc4f30eea59233d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/799cc92a2f706b95d6e8136b55400b10378ef83f655b24689bc4f30eea59233d?s=96&d=mm&r=g","caption":"FOCO Assessoria Empresarial"}}]}},"_links":{"self":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/posts\/22329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/comments?post=22329"}],"version-history":[{"count":0,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/posts\/22329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/media\/22420"}],"wp:attachment":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/media?parent=22329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/categories?post=22329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/tags?post=22329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}