{"id":17819,"date":"2022-08-05T06:45:17","date_gmt":"2022-08-05T09:45:17","guid":{"rendered":"https:\/\/www.valormais.com.br\/blog\/2018\/06\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/"},"modified":"2022-08-05T06:45:17","modified_gmt":"2022-08-05T09:45:17","slug":"curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp","status":"publish","type":"post","link":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/","title":{"rendered":"Curso de Operador de Retroescavadeiva na Zona Sul de SP"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice do Conte\u00fado<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Curso_de_Operador_de_Retroescavadeiva_na_Zona_Sul_de_SP\" >Curso de Operador de Retroescavadeiva na Zona Sul de SP<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Curso_de_Operador_de_Retroescavadeiva_na_Zona_Sul_de_SP-2\" >Curso de Operador de Retroescavadeiva na Zona Sul de SP<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Pense_nas_principais_duvidas_que_as_pessoas_tem_quando_estao_pensando_em_consumir_o_seu_produto_ou_servico_e_cite_aqui_as_principais_perguntas_e_as_respostas\" >Pense nas principais d\u00favidas que as pessoas tem quando est\u00e3o pensando em consumir o seu produto ou servi\u00e7o, e cite aqui as principais perguntas e as respostas.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Caso_seu_produto_ou_servico_ainda_nao_seja_conhecido_diga_para_que_ele_serve_quais_as_vantagens_em_relacao_aos_produtos_tradicionais_que_tipo_de_ajuda_ele_pode_oferecer_as_pessoas\" >Caso seu produto ou servi\u00e7o ainda n\u00e3o seja conhecido, diga para que ele serve, quais as vantagens em rela\u00e7\u00e3o aos produtos tradicionais, que tipo de ajuda ele pode oferecer as pessoas.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Se_voce_tem_um_negocio_fisico_informe_o_seu_horario_de_atendimento\" >Se voc\u00ea tem um neg\u00f3cio f\u00edsico, informe o seu hor\u00e1rio de atendimento.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Se_voce_tem_um_negocio_fisico_fale_um_pouco_sobre_suas_instalacoes_Diga_como_chegar_pontos_de_referencia_sua_estrutura_Enfim_tudo_que_acredita_ser_um_diferencial\" >Se voc\u00ea tem um neg\u00f3cio f\u00edsico, fale um pouco sobre suas instala\u00e7\u00f5es. Diga como chegar, pontos de refer\u00eancia, sua estrutura. Enfim, tudo que acredita ser um diferencial.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Quais_as_pessoas_que_normalmente_consomem_seu_produto_ou_servico\" >Quais as pessoas que normalmente consomem seu produto ou servi\u00e7o?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Voce_pode_dar_algum_tipo_de_desconto_para_quem_disser_que_te_encontrou_atraves_das_nossas_ferramentas_Se_sim_que_tipo_Pode_ser_algum_brinde_tambem\" >Voc\u00ea pode dar algum tipo de desconto para quem disser que te encontrou atrav\u00e9s das nossas ferramentas? Se sim, que tipo? Pode ser algum brinde tamb\u00e9m.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Se_coloque_no_lugar_do_seu_cliente_e_nos_conte_Porque_ele_deve_escolher_voce_ao_inves_do_seu_concorrente\" >Se coloque no lugar do seu cliente, e nos conte: Porque ele deve escolher voc\u00ea ao inv\u00e9s do seu concorrente.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#As_pessoas_costumam_pensar_bem_antes_de_consumir_algo_Quais_os_principais_cuidados_que_esta_pessoa_deve_ter_na_hora_de_escolher_onde_comprar_ou_de_quem_consumir_o_servico_que_voce_oferece\" >As pessoas costumam pensar bem antes de consumir algo: Quais os principais cuidados que esta pessoa deve ter na hora de escolher onde comprar ou de quem consumir o servi\u00e7o que voc\u00ea oferece.<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Curso_de_Operador_de_Retroescavadeiva_na_Zona_Sul_de_SP-3\" >Curso de Operador de Retroescavadeiva na Zona Sul de SP<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#Solicite_um_Orcamento\" >Solicite um Or\u00e7amento<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Curso_de_Operador_de_Retroescavadeiva_na_Zona_Sul_de_SP\"><\/span>Curso de Operador de Retroescavadeiva na Zona Sul de SP<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>Empresa:<\/strong> Civiltec Centro de Curso Industrial<br \/><strong>Telefone: <\/strong>11 4753-4181 | <br \/><strong>WhatsApp: <\/strong>11 94701-5398,         <br \/><strong>Site: <\/strong><a href=\"http:\/\/www.civiltec-cursos.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">www.civiltec-cursos.com.br<\/a><br \/><strong>Facebook:  <\/strong><a href=\"https:\/\/www.facebook.com\/Civiltec-Cursos-e-Treinamentos-1683094072002003\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.facebook.com\/Civiltec-Cursos-e-Treinamentos-1683094072002003\/<\/a><br \/><strong>Youtube: <\/strong><a href=\"https:\/\/www.youtube.com\/user\/ccitreinamentos\" target=\"_blank\" rel=\"noopener noreferrer\">www.youtube.com\/user\/ccitreinamentos<\/a><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Curso_de_Operador_de_Retroescavadeiva_na_Zona_Sul_de_SP-2\"><\/span>Curso de Operador de Retroescavadeiva na Zona Sul de SP<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O curso de Operador de Retroescavadeira visa capacitar o profissional na opera\u00e7\u00e3o adequada com a m\u00e1quina, por\u00e9m os aspectos de Seguran\u00e7a Operacional \u00e9 requisito necess\u00e1rio a qualquer operador independente do tempo de conhecimento em opera\u00e7\u00f5es com a m\u00e1quina. <\/p>\n<p>Temos Curso de Empilhadeira Retr\u00e1til, Retroescavadeira, Escavadeira Hidr\u00e1ulica, Mini Carregadeira \u2013 BobCat, Guindauto \u2013 Munck e P\u00e1 carregadeira.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pense_nas_principais_duvidas_que_as_pessoas_tem_quando_estao_pensando_em_consumir_o_seu_produto_ou_servico_e_cite_aqui_as_principais_perguntas_e_as_respostas\"><\/span>Pense nas principais d\u00favidas que as pessoas tem quando est\u00e3o pensando em consumir o seu produto ou servi\u00e7o, e cite aqui as principais perguntas e as respostas.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ol>\n<li>Escola Fornece Certificado? Sim, Certificado e Credencial.<\/li>\n<li>A Escola \u00e9 Reconhecida pelo MEC? Sim.<\/li>\n<li>S\u00e3o Quantos dias de Curso? Carga Hor\u00e1ria de 20 Horas (3 Dias)<\/li>\n<li>Que Dia Posso esta iniciando o Curso? Toda Quinta-Feira e S\u00e1bado se inicia turma em nossa escola.<\/li>\n<li>E a forma de pagamento? Pode esta acertando 50% do curso no inicio da Inscri\u00e7\u00e3o e 50% Restante antes da Aula pratica, tanto no Dinheiro ou Cart\u00e3o de Debito e Credito.<\/li>\n<li>E validade do Curso? Determinada conforme a Lei do Trabalho<\/li>\n<li>O Curso Cont\u00e9m Material did\u00e1tico? Sim, Apostila.<\/li>\n<li>O Curso \u00e9 Online, ou Presencial? Presencial<\/li>\n<li>Precisa pagar Taxa de Inscri\u00e7\u00e3o do Curso? N\u00e3o, j\u00e1 esta tudo Incluso no Valor do curso.<\/li>\n<li>Precisa comprovar alguma experi\u00eancia para fazer o curso? O Curso n\u00e3o exige Experi\u00eancia ou forma\u00e7\u00e3o.<\/li>\n<li>Qual Idade M\u00ednima para fazer o curso? 18 anos.<\/li>\n<\/ol>\n<h3><span class=\"ez-toc-section\" id=\"Caso_seu_produto_ou_servico_ainda_nao_seja_conhecido_diga_para_que_ele_serve_quais_as_vantagens_em_relacao_aos_produtos_tradicionais_que_tipo_de_ajuda_ele_pode_oferecer_as_pessoas\"><\/span>Caso seu produto ou servi\u00e7o ainda n\u00e3o seja conhecido, diga para que ele serve, quais as vantagens em rela\u00e7\u00e3o aos produtos tradicionais, que tipo de ajuda ele pode oferecer as pessoas.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Nossos cursos foram idealizados para que voc\u00ea se torne um profissional qualificado. Sua Vantagem \u00e9 a recompensa de um bom emprego, pois todos procuram e valorizam profissionais capacitados e formados.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Se_voce_tem_um_negocio_fisico_informe_o_seu_horario_de_atendimento\"><\/span>Se voc\u00ea tem um neg\u00f3cio f\u00edsico, informe o seu hor\u00e1rio de atendimento.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Segunda \u00e0 Sexta-Feira das 8 hrs \u00e0 17 hrs e aos S\u00e1bados 7 hrs \u00e0 12 hrs.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Se_voce_tem_um_negocio_fisico_fale_um_pouco_sobre_suas_instalacoes_Diga_como_chegar_pontos_de_referencia_sua_estrutura_Enfim_tudo_que_acredita_ser_um_diferencial\"><\/span>Se voc\u00ea tem um neg\u00f3cio f\u00edsico, fale um pouco sobre suas instala\u00e7\u00f5es. Diga como chegar, pontos de refer\u00eancia, sua estrutura. Enfim, tudo que acredita ser um diferencial.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>A Civiltec est\u00e1 Localizada na Av. Jo\u00e3o Barbosa Moraes N\u00b0 200 \u2013 Centro de Itaquaquecetuba-SP, Pr\u00f3ximo ao MC DONALD, Enfrente a escola Homero.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Quais_as_pessoas_que_normalmente_consomem_seu_produto_ou_servico\"><\/span> Quais as pessoas que normalmente consomem seu produto ou servi\u00e7o?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>S\u00e3o Pessoas F\u00edsicas e Jur\u00eddicas.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Voce_pode_dar_algum_tipo_de_desconto_para_quem_disser_que_te_encontrou_atraves_das_nossas_ferramentas_Se_sim_que_tipo_Pode_ser_algum_brinde_tambem\"><\/span> Voc\u00ea pode dar algum tipo de desconto para quem disser que te encontrou atrav\u00e9s das nossas ferramentas? Se sim, que tipo? Pode ser algum brinde tamb\u00e9m.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Sim, basta informar a palavra &#8220;VALORMAIS&#8221; e solicite seu desconto.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Se_coloque_no_lugar_do_seu_cliente_e_nos_conte_Porque_ele_deve_escolher_voce_ao_inves_do_seu_concorrente\"><\/span> Se coloque no lugar do seu cliente, e nos conte: Porque ele deve escolher voc\u00ea ao inv\u00e9s do seu concorrente.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>A Civiltec \u00e9 uma empresa prestadora de servi\u00e7os especializada em cursos e treinamentos para capacita\u00e7\u00e3o profissional industrial.<\/p>\n<p>Formamos operadores em diversos equipamentos como: Empilhadeira, Guindauto\/Munck, Escavadeira Hidr\u00e1ulica, Ponte Rolante, Retroescavadeira, Bob Cat ou Mini Carregadeira, P\u00e1 Carregadeira, Rolo Compactador.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"As_pessoas_costumam_pensar_bem_antes_de_consumir_algo_Quais_os_principais_cuidados_que_esta_pessoa_deve_ter_na_hora_de_escolher_onde_comprar_ou_de_quem_consumir_o_servico_que_voce_oferece\"><\/span>As pessoas costumam pensar bem antes de consumir algo: Quais os principais cuidados que esta pessoa deve ter na hora de escolher onde comprar ou de quem consumir o servi\u00e7o que voc\u00ea oferece.<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O futuro aluno deve considerar e analisar bem a escola onde pretende fazer sua capacita\u00e7\u00e3o, pois \u00e9 fundamental que a qualidade seja a maior poss\u00edvel, afinal o mercado preza pela qualidade do candidato aos postos de trabalho.<\/p>\n<p>Nem sempre o curso mais barato \u00e9 o melhor.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Curso_de_Operador_de_Retroescavadeiva_na_Zona_Sul_de_SP-3\"><\/span><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Curso de Operador de Retroescavadeiva na Zona Sul de SP<\/span><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><strong>Empresa:<\/strong> CiviltecCentro de Curso Industrial<br \/><strong>Telefone: <\/strong>11 4753-4181 | <br \/><strong>WhatsApp: <\/strong>11 94701-5398,   &#8211;  &#8211;  &#8211;  <br \/><strong>Site: <\/strong><a href=\"http:\/\/www.civiltec-cursos.com.br\" target=\"_blank\" rel=\"noopener noreferrer\">www.civiltec-cursos.com.br<\/a><br \/><strong>Facebook:  <\/strong><a href=\"http:\/\/www.facebook.com\/Civiltec-Cursos-e-Treinamentos-1683094072002003\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.facebook.com\/Civiltec-Cursos-e-Treinamentos-1683094072002003\/<\/a><br \/><strong>Youtube: <\/strong><a href=\"http:\/\/www.facebook.com\/Civiltec-Cursos-e-Treinamentos-1683094072002003\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.youtube.com\/user\/ccitreinamentos<\/a><\/p>\n<h3 style=\"margin-top: 25px;\"><span class=\"ez-toc-section\" id=\"Solicite_um_Orcamento\"><\/span>Solicite um Or\u00e7amento<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1033-o1\" lang=\"pt-BR\" dir=\"ltr\" data-wpcf7-id=\"1033\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/blog\/wp-json\/wp\/v2\/posts\/17819#wpcf7-f1033-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rios de contato\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1033\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_BR\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1033-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.6\" \/>\n<\/fieldset>\n<div style=\"display:none;\">\n\t<p><input type=\"hidden\" name=\"your-subject\" value=\"Or\u00e7amento\" \/>\n\t<span class=\"wpcf7-form-control-wrap URL\" data-name=\"URL\"><input type=\"hidden\" name=\"URL\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.valormais.com.br\/blog\/blog\/wp-json\/wp\/v2\/posts\/17819\"><\/span>\n\t<span class=\"wpcf7-form-control-wrap email_cliente\" data-name=\"email_cliente\"><input type=\"hidden\" name=\"email_cliente\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"contato@civiltec-cursos.com.br\"><\/span>\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-240-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefone\" value=\"\" type=\"text\" name=\"text-240-tel\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Digite aqui o que voc\u00ea precisa...\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p>[recaptcha]\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR OR\u00c7AMENTO\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on the_excerpt --><!-- AddThis Share Buttons generic via filter on the_excerpt --><\/p>\n","protected":false},"author":1,"featured_media":17804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"o","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[774],"tags":[126,2231],"class_list":["post-17819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-774","tag-cursos","tag-na-zona-sul-de-sp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec<\/title>\n<meta name=\"description\" content=\"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec\" \/>\n<meta property=\"og:description\" content=\"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"VALORMAIS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ValorMais\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-05T09:45:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2018\/06\/curso-retroescavadeira-em-sp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"857\" \/>\n\t<meta property=\"og:image:height\" content=\"511\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valormais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec\" \/>\n<meta name=\"twitter:description\" content=\"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva\" \/>\n<meta name=\"twitter:creator\" content=\"@valormais\" \/>\n<meta name=\"twitter:site\" content=\"@valormais\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valormais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/\"},\"author\":{\"name\":\"Valormais\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f37bb69e411437520d284b9115d09e20\"},\"headline\":\"Curso de Operador de Retroescavadeiva na Zona Sul de SP\",\"datePublished\":\"2022-08-05T09:45:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/\"},\"wordCount\":684,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/curso-retroescavadeira-em-sp.jpg\",\"keywords\":[\"Cursos\",\"na Zona Sul de SP\"],\"articleSection\":[\"-\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/\",\"url\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/\",\"name\":\"Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/curso-retroescavadeira-em-sp.jpg\",\"datePublished\":\"2022-08-05T09:45:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f37bb69e411437520d284b9115d09e20\"},\"description\":\"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/curso-retroescavadeira-em-sp.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/curso-retroescavadeira-em-sp.jpg\",\"width\":857,\"height\":511,\"caption\":\"Curso de Operador de Retroescavadeiva na Zona Oeste de SP Civiltec\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/774\\\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"-\",\"item\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/categorias\\\/774\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Curso de Operador de Retroescavadeiva na Zona Sul de SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/\",\"name\":\"VALORMAIS\",\"description\":\"Solu\u00e7\u00f5es Digitais Inovadoras\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valormais.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f37bb69e411437520d284b9115d09e20\",\"name\":\"Valormais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55f878cefc9c470b2d9b4c490c6fa7cf6bcae6ea43bd8e2cd81ab739588ad5f8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55f878cefc9c470b2d9b4c490c6fa7cf6bcae6ea43bd8e2cd81ab739588ad5f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55f878cefc9c470b2d9b4c490c6fa7cf6bcae6ea43bd8e2cd81ab739588ad5f8?s=96&d=mm&r=g\",\"caption\":\"Valormais\"},\"description\":\"Uma empresa formada por profissionais de Publicidade, Marketing, Internet e Tecnologia da Informa\u00e7\u00e3o. Constru\u00edmos solu\u00e7\u00f5es e relacionamentos inteligente para nossos parceiros.\",\"sameAs\":[\"https:\\\/\\\/www.valormais.com.br\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec","description":"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec","og_description":"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva","og_url":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/","og_site_name":"VALORMAIS","article_publisher":"https:\/\/www.facebook.com\/ValorMais","article_published_time":"2022-08-05T09:45:17+00:00","og_image":[{"width":857,"height":511,"url":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2018\/06\/curso-retroescavadeira-em-sp.jpg","type":"image\/jpeg"}],"author":"Valormais","twitter_card":"summary_large_image","twitter_title":"Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec","twitter_description":"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva","twitter_creator":"@valormais","twitter_site":"@valormais","twitter_misc":{"Escrito por":"Valormais","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#article","isPartOf":{"@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/"},"author":{"name":"Valormais","@id":"https:\/\/www.valormais.com.br\/blog\/#\/schema\/person\/f37bb69e411437520d284b9115d09e20"},"headline":"Curso de Operador de Retroescavadeiva na Zona Sul de SP","datePublished":"2022-08-05T09:45:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/"},"wordCount":684,"commentCount":0,"image":{"@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2018\/06\/curso-retroescavadeira-em-sp.jpg","keywords":["Cursos","na Zona Sul de SP"],"articleSection":["-"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/","url":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/","name":"Curso de Operador de Retroescavadeiva na Zona Sul de SP - Civiltec","isPartOf":{"@id":"https:\/\/www.valormais.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#primaryimage"},"image":{"@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2018\/06\/curso-retroescavadeira-em-sp.jpg","datePublished":"2022-08-05T09:45:17+00:00","author":{"@id":"https:\/\/www.valormais.com.br\/blog\/#\/schema\/person\/f37bb69e411437520d284b9115d09e20"},"description":"Curso de Operador de Retroescavadeiva na Zona Sul de SP. Ligue: 11 4753-4181 11 94701-5398. Civiltec Quanto custa em Zona Sul de SP Curso de Operador de Retroescavadeiva. Onde tem Cursos. Confira todos os servi\u00e7os e produtos que oferecemos para facilitar o seu dia a dia, solicite seu or\u00e7amento agora mesmo! Curso de Operador de Retroescavadeiva","breadcrumb":{"@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#primaryimage","url":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2018\/06\/curso-retroescavadeira-em-sp.jpg","contentUrl":"https:\/\/www.valormais.com.br\/blog\/wp-content\/uploads\/2018\/06\/curso-retroescavadeira-em-sp.jpg","width":857,"height":511,"caption":"Curso de Operador de Retroescavadeiva na Zona Oeste de SP Civiltec"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valormais.com.br\/blog\/774\/curso-de-operador-de-retroescavadeiva-na-zona-sul-de-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.valormais.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"-","item":"https:\/\/www.valormais.com.br\/blog\/categorias\/774\/"},{"@type":"ListItem","position":3,"name":"Curso de Operador de Retroescavadeiva na Zona Sul de SP"}]},{"@type":"WebSite","@id":"https:\/\/www.valormais.com.br\/blog\/#website","url":"https:\/\/www.valormais.com.br\/blog\/","name":"VALORMAIS","description":"Solu\u00e7\u00f5es Digitais Inovadoras","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valormais.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.valormais.com.br\/blog\/#\/schema\/person\/f37bb69e411437520d284b9115d09e20","name":"Valormais","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/55f878cefc9c470b2d9b4c490c6fa7cf6bcae6ea43bd8e2cd81ab739588ad5f8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55f878cefc9c470b2d9b4c490c6fa7cf6bcae6ea43bd8e2cd81ab739588ad5f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55f878cefc9c470b2d9b4c490c6fa7cf6bcae6ea43bd8e2cd81ab739588ad5f8?s=96&d=mm&r=g","caption":"Valormais"},"description":"Uma empresa formada por profissionais de Publicidade, Marketing, Internet e Tecnologia da Informa\u00e7\u00e3o. Constru\u00edmos solu\u00e7\u00f5es e relacionamentos inteligente para nossos parceiros.","sameAs":["https:\/\/www.valormais.com.br"]}]}},"_links":{"self":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/posts\/17819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/comments?post=17819"}],"version-history":[{"count":0,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/posts\/17819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/media\/17804"}],"wp:attachment":[{"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/media?parent=17819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/categories?post=17819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valormais.com.br\/blog\/wp-json\/wp\/v2\/tags?post=17819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}